{"id":11398,"date":"2014-06-06T15:37:57","date_gmt":"2014-06-06T14:37:57","guid":{"rendered":"http:\/\/www.fert.fr\/v2\/?p=11398"},"modified":"2024-01-24T09:24:44","modified_gmt":"2024-01-24T09:24:44","slug":"note-analyse-experience-paysans-relais","status":"publish","type":"post","link":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/","title":{"rendered":"Analytical note on the experience of farmers relay"},"content":{"rendered":"<section  class='av_textblock_section av-av_textblock-35972167d9f102c5ddaec0c531c98b9e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><!--:fr--><\/p>\n<p><!--:--><!--:en--><\/p>\n<p><!--:--><br \/>\n<!--:fr--><\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.calameo.com\/read\/0005163313ab7aa130215\" width=\"960\" height=\"640\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><!--:--><!--:en--><\/p>\n<p><!--:--><br \/>\n<!--:fr--><\/p>\n<p><!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_full  avia-builder-el-1  el_after_av_textblock  avia-builder-el-last  first flex_column_div av-zero-column-padding  column-top-margin'     ><div  class='avia-button-wrap av-av_button-eea690143e03c06049eda66d70756ba7-wrap avia-button-center  avia-builder-el-2  avia-builder-el-no-sibling '><a href='http:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-expe-paysans-relais_2012.pdf'  class='avia-button av-av_button-eea690143e03c06049eda66d70756ba7 av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-center avia-color-theme-color'   aria-label=\"Download this document\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue82d' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Download this document<\/span><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":30827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[654,816],"tags":[649,380],"actions-thematique":[],"ressources_action":[],"actualites_action":[],"actions_actions":[],"class_list":["post-11398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-en","category-non-classifiee-en","tag-madagascar-en","tag-organisations-de-producteurs","ressource-madagascar-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analytical note on the experience of farmers relay - Fert - agri-agence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analytical note on the experience of farmers relay - Fert - agri-agence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/\" \/>\n<meta property=\"og:site_name\" content=\"Fert - agri-agence\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-06T14:37:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T09:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"limbus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"limbus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/\"},\"author\":{\"name\":\"limbus\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/person\\\/d6b0c0a2902643b9c878656672de8fee\"},\"headline\":\"Analytical note on the experience of farmers relay\",\"datePublished\":\"2014-06-06T14:37:57+00:00\",\"dateModified\":\"2024-01-24T09:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/MDG_Note-analyse-paysans-relais_2012.jpg\",\"keywords\":[\"Madagascar\",\"Organisations de producteurs\"],\"articleSection\":[\"Non class\u00e9\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/\",\"name\":\"Analytical note on the experience of farmers relay - Fert - agri-agence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/MDG_Note-analyse-paysans-relais_2012.jpg\",\"datePublished\":\"2014-06-06T14:37:57+00:00\",\"dateModified\":\"2024-01-24T09:24:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/MDG_Note-analyse-paysans-relais_2012.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/MDG_Note-analyse-paysans-relais_2012.jpg\",\"width\":1181,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/note-analyse-experience-paysans-relais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analytical note on the experience of farmers relay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\",\"name\":\"Fert - agri-agence\",\"description\":\"Association de coop\u00e9ration agricole \u00e0 l&#039;international\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#organization\",\"name\":\"Fert\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/LOGO_rvb_OK1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/LOGO_rvb_OK1.jpg\",\"width\":1030,\"height\":1032,\"caption\":\"Fert\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/association-fert\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/person\\\/d6b0c0a2902643b9c878656672de8fee\",\"name\":\"limbus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g\",\"caption\":\"limbus\"},\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/author\\\/limbus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analytical note on the experience of farmers relay - Fert - agri-agence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/","og_locale":"en_US","og_type":"article","og_title":"Analytical note on the experience of farmers relay - Fert - agri-agence","og_url":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/","og_site_name":"Fert - agri-agence","article_published_time":"2014-06-06T14:37:57+00:00","article_modified_time":"2024-01-24T09:24:44+00:00","og_image":[{"width":1181,"height":1706,"url":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg","type":"image\/jpeg"}],"author":"limbus","twitter_card":"summary_large_image","twitter_misc":{"Written by":"limbus","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#article","isPartOf":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/"},"author":{"name":"limbus","@id":"https:\/\/www.fert.fr\/en\/#\/schema\/person\/d6b0c0a2902643b9c878656672de8fee"},"headline":"Analytical note on the experience of farmers relay","datePublished":"2014-06-06T14:37:57+00:00","dateModified":"2024-01-24T09:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/"},"wordCount":92,"publisher":{"@id":"https:\/\/www.fert.fr\/en\/#organization"},"image":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg","keywords":["Madagascar","Organisations de producteurs"],"articleSection":["Non class\u00e9","Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/","url":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/","name":"Analytical note on the experience of farmers relay - Fert - agri-agence","isPartOf":{"@id":"https:\/\/www.fert.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#primaryimage"},"image":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg","datePublished":"2014-06-06T14:37:57+00:00","dateModified":"2024-01-24T09:24:44+00:00","breadcrumb":{"@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#primaryimage","url":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg","contentUrl":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2014\/06\/MDG_Note-analyse-paysans-relais_2012.jpg","width":1181,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/www.fert.fr\/en\/note-analyse-experience-paysans-relais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fert.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Analytical note on the experience of farmers relay"}]},{"@type":"WebSite","@id":"https:\/\/www.fert.fr\/en\/#website","url":"https:\/\/www.fert.fr\/en\/","name":"Fert - agri-agence","description":"Association de coop\u00e9ration agricole \u00e0 l&#039;international","publisher":{"@id":"https:\/\/www.fert.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fert.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fert.fr\/en\/#organization","name":"Fert","url":"https:\/\/www.fert.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fert.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2012\/03\/LOGO_rvb_OK1.jpg","contentUrl":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2012\/03\/LOGO_rvb_OK1.jpg","width":1030,"height":1032,"caption":"Fert"},"image":{"@id":"https:\/\/www.fert.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/association-fert\/"]},{"@type":"Person","@id":"https:\/\/www.fert.fr\/en\/#\/schema\/person\/d6b0c0a2902643b9c878656672de8fee","name":"limbus","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7574c8637261273cebda8df473bd4a382c7cc782dea8e3c46ecc9c7692307ad0?s=96&d=mm&r=g","caption":"limbus"},"url":"https:\/\/www.fert.fr\/en\/author\/limbus\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/posts\/11398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/comments?post=11398"}],"version-history":[{"count":0,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/posts\/11398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/media\/30827"}],"wp:attachment":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/media?parent=11398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/categories?post=11398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/tags?post=11398"},{"taxonomy":"actions-thematique","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/actions-thematique?post=11398"},{"taxonomy":"ressources_action","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/ressources_action?post=11398"},{"taxonomy":"actualites_action","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/actualites_action?post=11398"},{"taxonomy":"actions_actions","embeddable":true,"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/actions_actions?post=11398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}