{"id":791,"count":8,"description":"","link":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/","name":"Tools and methods","slug":"outils_et_methodes-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Tools and methods - Fert - agri-agence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Tools and methods - Fert - agri-agence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Fert - agri-agence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/category\\\/outils_et_methodes-en\\\/\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/category\\\/outils_et_methodes-en\\\/\",\"name\":\"Archives des Tools and methods - Fert - agri-agence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/category\\\/outils_et_methodes-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/category\\\/outils_et_methodes-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tools and methods\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\",\"name\":\"Fert - agri-agence\",\"description\":\"Association de coop\u00e9ration agricole \u00e0 l&#039;international\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#organization\",\"name\":\"Fert\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/LOGO_rvb_OK1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fert.fr\\\/v2\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/LOGO_rvb_OK1.jpg\",\"width\":1030,\"height\":1032,\"caption\":\"Fert\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fert.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/association-fert\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Tools and methods - Fert - agri-agence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Tools and methods - Fert - agri-agence","og_url":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/","og_site_name":"Fert - agri-agence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/","url":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/","name":"Archives des Tools and methods - Fert - agri-agence","isPartOf":{"@id":"https:\/\/www.fert.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fert.fr\/en\/category\/outils_et_methodes-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fert.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Tools and methods"}]},{"@type":"WebSite","@id":"https:\/\/www.fert.fr\/en\/#website","url":"https:\/\/www.fert.fr\/en\/","name":"Fert - agri-agence","description":"Association de coop\u00e9ration agricole \u00e0 l&#039;international","publisher":{"@id":"https:\/\/www.fert.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fert.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fert.fr\/en\/#organization","name":"Fert","url":"https:\/\/www.fert.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fert.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2012\/03\/LOGO_rvb_OK1.jpg","contentUrl":"https:\/\/www.fert.fr\/v2\/wp-content\/uploads\/2012\/03\/LOGO_rvb_OK1.jpg","width":1030,"height":1032,"caption":"Fert"},"image":{"@id":"https:\/\/www.fert.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/association-fert\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/categories\/791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.fert.fr\/en\/wp-json\/wp\/v2\/posts?categories=791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}